{"id":18687,"date":"2024-10-11T14:12:11","date_gmt":"2024-10-11T19:12:11","guid":{"rendered":"https:\/\/dragonflycats.com\/?p=18687"},"modified":"2024-10-11T14:12:11","modified_gmt":"2024-10-11T19:12:11","slug":"sida-et-leucemie-feline","status":"publish","type":"post","link":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/","title":{"rendered":"Sida et Leuc\u00e9mie F\u00e9line"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/dragonflycats.com\/wp-content\/uploads\/2024\/10\/Picture1.png\u00a0\u00bb title_text=\u00a0\u00bbPicture1&Prime; _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; custom_padding=\u00a0\u00bb7px||11px|||\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.21.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Le FIV (sida) et le FELV (leuc\u00e9mie) sont deux maladies qui tuent des milliers de chats annuellement. La transmission s&rsquo;effectue par les fluides corporels tel que salive, sang et excr\u00e9ments. Il s\u2019agit d\u2019une infection par retrovirus qui, en se d\u00e9veloppant dans l\u2019organisme, va provoquer l\u2019immunod\u00e9ficience et infections secondaires et cancer.<\/p>\n<p>Tout \u00e9leveur consciencieux fera tester chaque reproducteur et sera en mesure de vous fournir la preuve que sa chatterie est n\u00e9gative. Il n\u2019y a \u00e0 ce jour aucune traitement connu .\u00a0<\/p>\n<p>L&rsquo;animal durant toute sa vie, demeurera porteur et risquera de transmettre la maladie \u00e0 un autre chat. Tous les chats porteurs ou souffrant de ces maladies en d\u00e9c\u00e8dent t\u00f4t ou tard. Pour certains, la maladie peut \u00eatre dormante mais cela n\u2019emp\u00eachera pas la transmission.<\/p>\n<p>En tant qu&rsquo;acheteur, il est important de s\u2019assurer que le chaton est exempt de ces deux maladies lors de l\u2019achat. L\u2019 \u00e9leveur devrait \u00eatre en mesure de vous donner la preuve que les parents ou le chaton sont n\u00e9gatifs et de vous offrir une garantie \u00e0 cet effet.<\/p>\n<p>Lors du premier rendez-vous v\u00e9t\u00e9rinaire de votre chaton nous recommandons toujours la prise de sang commun\u00e9ment appel\u00e9 snap test et particuli\u00e8rement dans les 10 jours suivant la prise de possession. La prise de sang est peu dispendieuse, ne prend que quelques minutes et vous assure de la bonne sant\u00e9 de votre chaton<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le FIV (sida) et le FELV (leuc\u00e9mie) sont deux maladies qui tuent des milliers de chats annuellement. La transmission s&rsquo;effectue par les fluides corporels tel que salive, sang et excr\u00e9ments. Il s\u2019agit d\u2019une infection par retrovirus qui, en se d\u00e9veloppant dans l\u2019organisme, va provoquer l\u2019immunod\u00e9ficience et infections secondaires et cancer. Tout \u00e9leveur consciencieux fera tester chaque reproducteur et sera en mesure de vous fournir la preuve que sa chatterie est n\u00e9gative. Il n\u2019y a \u00e0 ce jour aucune traitement connu .\u00a0 L&rsquo;animal durant toute sa vie, demeurera porteur et risquera de transmettre la maladie \u00e0 un autre chat. Tous les chats porteurs ou souffrant de ces maladies en d\u00e9c\u00e8dent t\u00f4t ou tard. Pour certains, la maladie peut \u00eatre dormante mais cela n\u2019emp\u00eachera pas la transmission. En tant qu&rsquo;acheteur, il est important de s\u2019assurer que le chaton est exempt de ces deux maladies lors de l\u2019achat. L\u2019 \u00e9leveur devrait \u00eatre en mesure de vous donner la preuve que les parents ou le chaton sont n\u00e9gatifs et de vous offrir une garantie \u00e0 cet effet. Lors du premier rendez-vous v\u00e9t\u00e9rinaire de votre chaton nous recommandons toujours la prise de sang commun\u00e9ment appel\u00e9 snap test et particuli\u00e8rement dans les 10 jours suivant la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-18687","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sida et Leuc\u00e9mie F\u00e9line - DragonFlyCats<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sida et Leuc\u00e9mie F\u00e9line\" \/>\n<meta property=\"og:description\" content=\"Le FIV (sida) et le FELV (leuc\u00e9mie) sont deux maladies qui tuent des milliers de chats annuellement. La transmission s&#039;effectue par les fluides corporels tel que salive, sang et excr\u00e9ments. Il s\u2019agit d\u2019une infection par retrovirus qui, en se d\u00e9veloppant dans l\u2019organisme, va provoquer l\u2019immunod\u00e9ficience et infections secondaires et cancer. Tout \u00e9leveur consciencieux fera tester chaque reproducteur et sera en mesure de vous fournir la preuve que sa chatterie est n\u00e9gative. Il n\u2019y a \u00e0 ce jour aucune traitement connu .\u00a0 L&#039;animal durant toute sa vie, demeurera porteur et risquera de transmettre la maladie \u00e0 un autre chat. Tous les chats porteurs ou souffrant de ces maladies en d\u00e9c\u00e8dent t\u00f4t ou tard. Pour certains, la maladie peut \u00eatre dormante mais cela n\u2019emp\u00eachera pas la transmission. En tant qu&#039;acheteur, il est important de s\u2019assurer que le chaton est exempt de ces deux maladies lors de l\u2019achat. L\u2019 \u00e9leveur devrait \u00eatre en mesure de vous donner la preuve que les parents ou le chaton sont n\u00e9gatifs et de vous offrir une garantie \u00e0 cet effet. Lors du premier rendez-vous v\u00e9t\u00e9rinaire de votre chaton nous recommandons toujours la prise de sang commun\u00e9ment appel\u00e9 snap test et particuli\u00e8rement dans les 10 jours suivant la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/\" \/>\n<meta property=\"og:site_name\" content=\"DragonFlyCats\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dragonflycats\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-11T19:12:11+00:00\" \/>\n<meta name=\"author\" content=\"Gabriell Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriell Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/\"},\"author\":{\"name\":\"Gabriell Martin\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#\\\/schema\\\/person\\\/1f265a39848e96bec81cc4f0e09fdc02\"},\"headline\":\"Sida et Leuc\u00e9mie F\u00e9line\",\"datePublished\":\"2024-10-11T19:12:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#organization\"},\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/\",\"url\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/\",\"name\":\"Sida et Leuc\u00e9mie F\u00e9line - DragonFlyCats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#website\"},\"datePublished\":\"2024-10-11T19:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/sida-et-leucemie-feline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sida et Leuc\u00e9mie F\u00e9line\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/\",\"name\":\"DragonFlyCats\",\"description\":\"Devon Rex - Savannah F1 - Griffon Bruxellois\",\"publisher\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#organization\",\"name\":\"Dragonflycats\",\"url\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/dragonflycats.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Logo-Dragonfly-cats-Black.png?fit=2560%2C1248&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/dragonflycats.com\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Logo-Dragonfly-cats-Black.png?fit=2560%2C1248&ssl=1\",\"width\":2560,\"height\":1248,\"caption\":\"Dragonflycats\"},\"image\":{\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dragonflycats\\\/\",\"https:\\\/\\\/www.instagram.com\\\/dragonflycats\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dragonflycats.com\\\/fr\\\/#\\\/schema\\\/person\\\/1f265a39848e96bec81cc4f0e09fdc02\",\"name\":\"Gabriell Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g\",\"caption\":\"Gabriell Martin\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sida et Leuc\u00e9mie F\u00e9line - DragonFlyCats","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/","og_locale":"fr_FR","og_type":"article","og_title":"Sida et Leuc\u00e9mie F\u00e9line","og_description":"Le FIV (sida) et le FELV (leuc\u00e9mie) sont deux maladies qui tuent des milliers de chats annuellement. La transmission s'effectue par les fluides corporels tel que salive, sang et excr\u00e9ments. Il s\u2019agit d\u2019une infection par retrovirus qui, en se d\u00e9veloppant dans l\u2019organisme, va provoquer l\u2019immunod\u00e9ficience et infections secondaires et cancer. Tout \u00e9leveur consciencieux fera tester chaque reproducteur et sera en mesure de vous fournir la preuve que sa chatterie est n\u00e9gative. Il n\u2019y a \u00e0 ce jour aucune traitement connu .\u00a0 L'animal durant toute sa vie, demeurera porteur et risquera de transmettre la maladie \u00e0 un autre chat. Tous les chats porteurs ou souffrant de ces maladies en d\u00e9c\u00e8dent t\u00f4t ou tard. Pour certains, la maladie peut \u00eatre dormante mais cela n\u2019emp\u00eachera pas la transmission. En tant qu'acheteur, il est important de s\u2019assurer que le chaton est exempt de ces deux maladies lors de l\u2019achat. L\u2019 \u00e9leveur devrait \u00eatre en mesure de vous donner la preuve que les parents ou le chaton sont n\u00e9gatifs et de vous offrir une garantie \u00e0 cet effet. Lors du premier rendez-vous v\u00e9t\u00e9rinaire de votre chaton nous recommandons toujours la prise de sang commun\u00e9ment appel\u00e9 snap test et particuli\u00e8rement dans les 10 jours suivant la [&hellip;]","og_url":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/","og_site_name":"DragonFlyCats","article_publisher":"https:\/\/www.facebook.com\/dragonflycats\/","article_published_time":"2024-10-11T19:12:11+00:00","author":"Gabriell Martin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gabriell Martin","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/#article","isPartOf":{"@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/"},"author":{"name":"Gabriell Martin","@id":"https:\/\/dragonflycats.com\/fr\/#\/schema\/person\/1f265a39848e96bec81cc4f0e09fdc02"},"headline":"Sida et Leuc\u00e9mie F\u00e9line","datePublished":"2024-10-11T19:12:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/dragonflycats.com\/fr\/#organization"},"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/","url":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/","name":"Sida et Leuc\u00e9mie F\u00e9line - DragonFlyCats","isPartOf":{"@id":"https:\/\/dragonflycats.com\/fr\/#website"},"datePublished":"2024-10-11T19:12:11+00:00","breadcrumb":{"@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dragonflycats.com\/fr\/sida-et-leucemie-feline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dragonflycats.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sida et Leuc\u00e9mie F\u00e9line"}]},{"@type":"WebSite","@id":"https:\/\/dragonflycats.com\/fr\/#website","url":"https:\/\/dragonflycats.com\/fr\/","name":"DragonFlyCats","description":"Devon Rex - Savannah F1 - Griffon Bruxellois","publisher":{"@id":"https:\/\/dragonflycats.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dragonflycats.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dragonflycats.com\/fr\/#organization","name":"Dragonflycats","url":"https:\/\/dragonflycats.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dragonflycats.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/dragonflycats.com\/wp-content\/uploads\/2020\/08\/Logo-Dragonfly-cats-Black.png?fit=2560%2C1248&ssl=1","contentUrl":"https:\/\/i0.wp.com\/dragonflycats.com\/wp-content\/uploads\/2020\/08\/Logo-Dragonfly-cats-Black.png?fit=2560%2C1248&ssl=1","width":2560,"height":1248,"caption":"Dragonflycats"},"image":{"@id":"https:\/\/dragonflycats.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dragonflycats\/","https:\/\/www.instagram.com\/dragonflycats\/"]},{"@type":"Person","@id":"https:\/\/dragonflycats.com\/fr\/#\/schema\/person\/1f265a39848e96bec81cc4f0e09fdc02","name":"Gabriell Martin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e14333624b1611d5b08683c0c192ec613531b4ef7f50ecc83af59bad1c24249?s=96&d=mm&r=g","caption":"Gabriell Martin"}}]}},"_links":{"self":[{"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/posts\/18687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/comments?post=18687"}],"version-history":[{"count":0,"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/posts\/18687\/revisions"}],"wp:attachment":[{"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/media?parent=18687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/categories?post=18687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dragonflycats.com\/fr\/wp-json\/wp\/v2\/tags?post=18687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}